{"id":232356,"date":"2021-10-12T10:00:00","date_gmt":"2021-10-12T08:00:00","guid":{"rendered":"https:\/\/www.growbarato.net\/blog\/?p=232356"},"modified":"2026-05-27T14:31:58","modified_gmt":"2026-05-27T12:31:58","slug":"bho-extraktion-aus-marihuana-mit-gas","status":"publish","type":"post","link":"https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/","title":{"rendered":"BHO-Extraktion aus Marihuana mit Gas"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">Das <\/span><strong><a href=\"https:\/\/www.growbarato.net\/255-bho-extracciones\" target=\"_blank\" rel=\"noopener\"><i>Butane Hash Oil<\/i> oder BHO<\/a><\/strong><span style=\"font-weight: 400;\"> ist eine Art der Cannabis-Extraktion, die aus dem \u00d6l gewonnen wird, das die Pflanze durch die Verwendung von <strong>Butangas<\/strong> bei der Herstellung freisetzt. Es kann sowohl trockenes als auch gefrorenes Pflanzenmaterial verwendet werden, um das Endprodukt zu erhalten. In diesem Artikel erfahren Sie, wie Sie eine BHO-Extraktion mit Marihuana sicher und effektiv durchf\u00fchren.<\/span><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a97f825a69dc\" class=\"ez-toc-cssicon-toggle-label\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97f825a69dc\"  \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/#Materialien_fuer_die_BHO-Extraktion\" >Materialien f\u00fcr die BHO-Extraktion<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/#Wie_man_eine_BHO-Marihuana-Gasextraktion_durchfuehrt\" >Wie man eine BHO-Marihuana-Gasextraktion durchf\u00fchrt<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/#Schritte_zur_Vakuumreinigung_von_BHO\" >Schritte zur Vakuumreinigung von BHO<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/#Wie_man_eine_BHO-Extraktion_verwendet\" >Wie man eine BHO-Extraktion verwendet<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/#Warnungen_und_Empfehlungen\" >Warnungen und Empfehlungen<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Materialien_fuer_die_BHO-Extraktion\"><\/span>Materialien f\u00fcr die BHO-Extraktion<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Um eine BHO-Extraktion korrekt durchzuf\u00fchren, ist es wichtig, in einem <strong>perfekt bel\u00fcfteten Bereich<\/strong> zu arbeiten, wie zum Beispiel auf einem Balkon oder einer Terrasse. Sobald Sie Ihren Arbeitsplatz eingerichtet haben, m\u00fcssen Sie die <strong>folgenden Materialien<\/strong> bereitlegen:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.growbarato.net\/bho-extracciones\/1256-gas-clipper-0-impurezas-bho.html\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Clipper-Gas<\/span><\/a><span style=\"font-weight: 400;\"> oder <strong>Butangas<\/strong><\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Ein <\/span><strong><a href=\"https:\/\/www.gbthegreenbrand.despues-de-la-cosecha\/765-gasolinator-extraccion-resinas-bho.html\">Extraktionsrohr<\/a><\/strong><span style=\"font-weight: 400;\"> f\u00fcr BHO<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Papierfilter<\/strong><\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Arbeitshandschuhe<\/strong><\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Ein gro\u00dfes <strong>Glasgef\u00e4\u00df<\/strong><\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Das <strong>Pflanzenmaterial<\/strong> Ihrer Wahl<\/span><\/li>\n<\/ul>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wie_man_eine_BHO-Marihuana-Gasextraktion_durchfuehrt\"><\/span>Wie man eine BHO-Marihuana-Gasextraktion durchf\u00fchrt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-39.jpg\" alt=\"bho extract\" class=\"wp-image-132532\" srcset=\"https:\/\/www.gbthegreenbrand.de\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-39.jpg 1000w, https:\/\/www.gbthegreenbrand.de\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-39-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.de\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-39-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Im Folgenden werden die Schritte erl\u00e4utert, um das <\/span><span style=\"font-weight: 400;\"><strong>Cannabis-Konzentrat BHO<\/strong> zu erhalten:<\/span><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\"><strong>Zerkleinern Sie Ihr Pflanzenmaterial<\/strong> mit Hilfe eines Grinders oder einer M\u00fchle.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Setzen Sie einen Filter<\/strong> in das Extraktionsrohr ein und <strong>f\u00fcllen Sie es mit Ihrem zerkleinerten Gras<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Verschlie\u00dfen Sie<\/strong> das Extraktionsrohr fest.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Stellen Sie das Glasgef\u00e4\u00df auf eine <strong>ebene Fl\u00e4che<\/strong> oder einen Tisch.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Ziehen Sie die Handschuhe an und halten Sie das Rohr<\/strong> mit der Austritts\u00f6ffnung nach unten, also in Richtung des Glasgef\u00e4\u00dfes.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Setzen Sie das Ventil der Gasdose<\/strong> in den oberen Teil des Rohrs ein und dr\u00fccken Sie es fest, damit es sich f\u00fcllt. Das fl\u00fcssige Gas beginnt, <strong>in das Glasgef\u00e4\u00df zu flie\u00dfen<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Wenn kein Gas mehr vorhanden ist, lassen Sie das Extraktionsrohr an einem <strong>sicheren Ort<\/strong>, au\u00dferhalb der Reichweite Dritter.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Sie werden sehen, dass die Fl\u00fcssigkeit im Gef\u00e4\u00df <strong>blubbert<\/strong>. Das bedeutet, dass das Gas verdampft.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Damit es schneller verdampft<\/strong>, k\u00f6nnen Sie das Glasgef\u00e4\u00df in ein gr\u00f6\u00dferes Gef\u00e4\u00df mit <strong>hei\u00dfem Wasser<\/strong> stellen, da die W\u00e4rme das Blubbern erzeugt.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Wenn die Fl\u00fcssigkeit <strong>aufh\u00f6rt zu blubbern<\/strong>, lassen Sie das Produkt etwa <strong>24 Stunden<\/strong> ruhen. Nach dieser Zeit ist Ihr BHO <strong>gebrauchsfertig<\/strong>.<\/span><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Schritte_zur_Vakuumreinigung_von_BHO\"><\/span>Schritte zur Vakuumreinigung von BHO<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Falls Sie \u00fcber eine <strong>Vakuumkammer und -pumpe<\/strong> verf\u00fcgen, k\u00f6nnen Sie das restliche Gas wie folgt aus dem Produkt entfernen:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Legen Sie das BHO auf ein <strong>Silikontablett auf Backpapier<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Stellen Sie das <strong>Tablett in die Vakuumkammer<\/strong> und stellen Sie sicher, dass es eben steht.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Beginnen Sie mit der Anwendung von <strong>sanfter und gleichm\u00e4\u00dfiger W\u00e4rme<\/strong>. Die ideale Temperatur variiert, liegt aber im Allgemeinen zwischen <strong>90 \u00b0C und 110 \u00b0C<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Verwenden Sie eine <strong>Heizplatte oder Heizmatten<\/strong>, um die Temperatur pr\u00e4zise zu steuern.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Schalten Sie die Vakuumpumpe ein<\/strong> und beginnen Sie, die Luft aus der Kammer zu entfernen. Dies erzeugt ein Vakuum, das die Entfernung der L\u00f6sungsmittel erleichtert.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">W\u00e4hrend das BHO gereinigt wird, \u00e4ndert es seine Konsistenz von <strong>fl\u00fcssig zu einem viskoseren Zustand<\/strong> und schlie\u00dflich zu einer <strong>festen Textur<\/strong> wie <strong><em>Shatter<\/em> oder <em>Wax<\/em><\/strong>.<\/span><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Wenn Sie der Meinung sind, dass der Reinigungsprozess abgeschlossen ist, <strong>schalten Sie die Vakuumpumpe und die W\u00e4rmequelle aus<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Lassen Sie das BHO auf <strong>Raumtemperatur<\/strong> abk\u00fchlen, bevor Sie es handhaben.<\/span><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wie_man_eine_BHO-Extraktion_verwendet\"><\/span>Wie man eine BHO-Extraktion verwendet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">BHO <\/span><span style=\"font-weight: 400;\">besitzt aufgrund seiner hohen Zusammensetzung an Cannabinoiden wie CBD und THC verschiedene<\/span><span style=\"font-weight: 400;\"> therapeutische Eigenschaften. Eine der <strong>einfachsten Arten, dieses Konzentrat zu verwenden<\/strong>, ist das <strong>Auftragen auf ein Zigarettenpapier<\/strong>, um einen Joint zu drehen.<\/span><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"450\" src=\"https:\/\/www.growbarato.net\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-40.jpg\" alt=\"vaporizing bho\" class=\"wp-image-132538\" srcset=\"https:\/\/www.gbthegreenbrand.de\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-40.jpg 1000w, https:\/\/www.gbthegreenbrand.de\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-40-300x135.jpg 300w, https:\/\/www.gbthegreenbrand.de\/blog\/wp-content\/uploads\/2021\/10\/Interior-GB-2.0-40-768x346.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Ebenso k\u00f6nnen Sie es mit einem <strong>Vaporizer, wie dem <a href=\"https:\/\/www.growbarato.net\/puffco\/7261-puffco-plus.html\" target=\"_blank\" rel=\"noopener\">Puffco Plus Vaporizer<\/a>, zusammen mit Ihrem bevorzugten E-Liquid<\/strong> verwenden. Dies ist eine <strong>diskrettere, effizientere und k\u00f6stlichere<\/strong> Art, Ihr BHO zu genie\u00dfen. Eine weitere interessante Methode ist die orale Einnahme.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Warnungen_und_Empfehlungen\"><\/span>Warnungen und Empfehlungen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Wie bereits erw\u00e4hnt, ist die BHO-Marihuana-Gasextraktion <strong>die gef\u00e4hrlichste von allen<\/strong>, da bei der Herstellung mit Gas hantiert wird. Deshalb geben wir die folgenden Empfehlungen, um dies zu einem <strong>vollkommen sicheren Prozess<\/strong> zu machen:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\"><strong>Rauchen Sie nicht<\/strong> im Arbeitsbereich oder in dessen unmittelbarer N\u00e4he. Das Gas ist extrem <strong>gef\u00e4hrlich und entflammbar<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Es wird nicht empfohlen, <strong>elektrische Ger\u00e4te ein- oder auszuschalten<\/strong>.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Wenn Sie den Extraktionsprozess abgeschlossen haben, <strong>warten Sie, bis das Gef\u00e4\u00df Raumtemperatur erreicht hat<\/strong>, bevor Sie es zur Reinigung handhaben.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\"><strong>Lagern Sie das BHO in kleinen Glasgef\u00e4\u00dfen<\/strong>, um es vor \u00e4u\u00dferen Einfl\u00fcssen zu sch\u00fctzen.<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Jetzt, da Sie wissen, wie man eine BHO-Marihuana-Gasextraktion durchf\u00fchrt, k\u00f6nnen Sie die <strong>Vorteile sowie die therapeutischen und medizinischen Eigenschaften<\/strong> dieses Konzentrats nutzen. Es sei jedoch daran erinnert, dass Cannabis-Extraktionen mit einem <strong>hohen THC-Gehalt unerw\u00fcnschte Nebenwirkungen hervorrufen k\u00f6nnen<\/strong>, die die Gesundheit des Benutzers beeintr\u00e4chtigen. Vergessen Sie nicht, unseren <strong><a href=\"https:\/\/www.growbarato.net\/\" target=\"_blank\" rel=\"noopener\">Online-Growshop<\/a><\/strong> zu besuchen, um mehr \u00fcber die besten Produkte und Zubeh\u00f6rteile zu erfahren, mit denen Sie Ihre zuk\u00fcnftigen BHO-Extraktionen auf die n\u00e4chste Stufe heben k\u00f6nnen.<\/span><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Das Butane Hash Oil oder BHO ist eine Art der Cannabis-Extraktion, die aus dem \u00d6l gewonnen wird, das die Pflanze durch die Verwendung von Butangas bei der Herstellung freisetzt. Es kann sowohl trockenes als auch gefrorenes Pflanzenmaterial verwendet werden, um das Endprodukt zu erhalten. In diesem Artikel erfahren Sie, wie Sie eine BHO-Extraktion mit Marihuana\u2026 <span class=\"leermas\" onclick=\"window.location.href='https:\/\/www.gbthegreenbrand.de\/blog\/bho-extraktion-aus-marihuana-mit-gas\/'\">Weiterlesen<\/span ><\/p>\n","protected":false},"author":18,"featured_media":232353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[2068,10,1],"tags":[],"class_list":{"0":"post-232356","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tipps","8":"category-consejos-sobre-como-cultivar","9":"category-noticias-marihuana"},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":9,"sum_votes":42},"_links":{"self":[{"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/posts\/232356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/comments?post=232356"}],"version-history":[{"count":4,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/posts\/232356\/revisions"}],"predecessor-version":[{"id":232675,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/posts\/232356\/revisions\/232675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/media\/232353"}],"wp:attachment":[{"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/media?parent=232356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/categories?post=232356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gbthegreenbrand.de\/blog\/wp-json\/wp\/v2\/tags?post=232356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}